{"id":7184,"date":"2025-07-29T13:53:41","date_gmt":"2025-07-29T13:53:41","guid":{"rendered":"https:\/\/mdxcro.com\/?page_id=7184"},"modified":"2026-06-03T06:39:59","modified_gmt":"2026-06-03T06:39:59","slug":"recursos","status":"publish","type":"page","link":"https:\/\/mdxcro.com\/es\/recursos\/","title":{"rendered":"Recursos"},"content":{"rendered":"\n<section id=\"block_802a6c954c11482ba4eebbac89278318\" class=\"hero hero--with-form\">\n    <div class=\"hero--bg\">\n      <img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/04\/Services-MDx-CRO.webp\" fetchpriority=\"high\" class=\"no-lazy\" alt=\"\" \/>\n    <\/div>\n        <div class=\"container\">\n                <div class=\"hero__grid\">\n            <div class=\"hero__content-col\">\n                <div class=\"content\">\n                                    <h1 class=\"title\">Blog y recursos<\/h1>\n            \n                            <div class=\"description\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Resumen regulatorio mensual y recursos gratuitos; leemos y analizamos las normativas para que usted no tenga que hacerlo.<\/p>\n<ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\">\n<li class=\"whitespace-normal break-words pl-2\">Art\u00edculos semanales con actualizaciones y recursos<\/li>\n<li class=\"whitespace-normal break-words pl-2\">Bolet\u00edn mensual con lo m\u00e1s destacado<\/li>\n<li class=\"whitespace-normal break-words pl-2\">Invitaciones a seminarios web y actualizaciones de eventos<\/li>\n<li class=\"whitespace-normal break-words pl-2\">Acceso completo al archivo, todas las entradas del blog y libros blancos<\/li>\n<\/ul>\n<\/div>\n            \n                                    <\/div>\n            <\/div>\n            <div class=\"hero__form-col mdx-form-wrapper\">\n                <style id=\"wpforms-css-vars-9888\">\n\t\t\t\t#wpforms-9888 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-9888\"><form id=\"wpforms-form-9888\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"9888\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/7184\" data-token=\"bb06b5e53b35ef8a21d0caed0ef19693\" data-token-time=\"1788355984\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-9888-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-9888-field_1\" >URL Name Name<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-9888-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-9888-field_12-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"12\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-9888-field_12\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][12][first]\" placeholder=\"First Name\" aria-errormessage=\"wpforms-9888-field_12-error\" required><label for=\"wpforms-9888-field_12\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-9888-field_12-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][12][last]\" placeholder=\"Last Name\" aria-errormessage=\"wpforms-9888-field_12-last-error\" required><label for=\"wpforms-9888-field_12-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-9888-field_13-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"13\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-9888-field_13\" aria-hidden=\"false\">Company Name<\/label><input type=\"text\" id=\"wpforms-9888-field_13\" class=\"wpforms-field-large\" name=\"wpforms[fields][13]\" placeholder=\"Company Name\" aria-errormessage=\"wpforms-9888-field_13-error\" ><\/div><div id=\"wpforms-9888-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-9888-field_2\" aria-hidden=\"false\">Email Address <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-9888-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Email Address\" spellcheck=\"false\" aria-errormessage=\"wpforms-9888-field_2-error\" required><\/div><div id=\"wpforms-9888-field_3-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"3\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Checkboxes <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-9888-field_3\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-9888-field_3_1\" name=\"wpforms[fields][3][]\" value=\"I have read and acknowledge the &lt;a href=&quot;\/privacy-policy&quot; target=&quot;_blank&quot;&gt;privacy policy&lt;\/a&gt; notice and consent to receive information from MDX.\" aria-errormessage=\"wpforms-9888-field_3_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-9888-field_3_1\">I have read and acknowledge the <a href=\"\/privacy-policy\" target=\"_blank\">privacy policy<\/a> notice and consent to receive information from MDX.<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-9888-field_17-container\" class=\"wpforms-field wpforms-field-html\" data-field-type=\"html\" data-field-id=\"17\"><div id=\"wpforms-9888-field_17\" aria-errormessage=\"wpforms-9888-field_17-error\"><input type='hidden' id=\"zc_gad\" name=\"zc_gad\" value=\"\"\/><\/div><\/div><div id=\"wpforms-9888-field_4-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-type=\"hidden\" data-field-id=\"4\"><input type=\"hidden\" id=\"wpforms-9888-field_4\" name=\"wpforms[fields][4]\"><\/div><div id=\"wpforms-9888-field_16-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-type=\"hidden\" data-field-id=\"16\"><input type=\"hidden\" id=\"wpforms-9888-field_16\" name=\"wpforms[fields][16]\" value=\"Newsletter\"><\/div><div id=\"wpforms-9888-field_6-container\" class=\"wpforms-field wpforms-field-hidden mdx-utm_source\" data-field-type=\"hidden\" data-field-id=\"6\"><input type=\"hidden\" id=\"wpforms-9888-field_6\" name=\"wpforms[fields][6]\"><\/div><div id=\"wpforms-9888-field_9-container\" class=\"wpforms-field wpforms-field-hidden mdx-utm_term\" data-field-type=\"hidden\" data-field-id=\"9\"><input type=\"hidden\" id=\"wpforms-9888-field_9\" name=\"wpforms[fields][9]\"><\/div><div id=\"wpforms-9888-field_7-container\" class=\"wpforms-field wpforms-field-hidden mdx-utm_medium\" data-field-type=\"hidden\" data-field-id=\"7\"><input type=\"hidden\" id=\"wpforms-9888-field_7\" name=\"wpforms[fields][7]\"><\/div><div id=\"wpforms-9888-field_8-container\" class=\"wpforms-field wpforms-field-hidden mdx-utm_campaign\" data-field-type=\"hidden\" data-field-id=\"8\"><input type=\"hidden\" id=\"wpforms-9888-field_8\" name=\"wpforms[fields][8]\"><\/div><div id=\"wpforms-9888-field_15-container\" class=\"wpforms-field wpforms-field-hidden mdx-utm_content\" data-field-type=\"hidden\" data-field-id=\"15\"><input type=\"hidden\" id=\"wpforms-9888-field_15\" name=\"wpforms[fields][15]\"><\/div><div id=\"wpforms-9888-field_18-container\" class=\"wpforms-field wpforms-field-hidden mdx-gclid\" data-field-type=\"hidden\" data-field-id=\"18\"><input type=\"hidden\" id=\"wpforms-9888-field_18\" name=\"wpforms[fields][18]\"><\/div><div id=\"wpforms-9888-field_19-container\" class=\"wpforms-field wpforms-field-hidden mdx-tracking_status\" data-field-type=\"hidden\" data-field-id=\"19\"><input type=\"hidden\" id=\"wpforms-9888-field_19\" name=\"wpforms[fields][19]\"><\/div><div id=\"wpforms-9888-field_20-container\" class=\"wpforms-field wpforms-field-hidden mdx-first_url\" data-field-type=\"hidden\" data-field-id=\"20\"><input type=\"hidden\" id=\"wpforms-9888-field_20\" name=\"wpforms[fields][20]\"><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-9888-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-9888-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-9888-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"9888\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/pages\/7184\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-9888\" class=\"wpforms-submit\" data-alt-text=\"Subscribing\" data-submit-text=\"Subscribe to our Newsletter\" aria-live=\"assertive\" value=\"wpforms-submit\">Subscribe to our Newsletter<\/button><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->            <\/div>\n        <\/div>\n            <\/div>\n<\/section>\n\n\n\n<section id=\"block_df1cdf927de3a84e9f9e751eb90dd21e\" class=\"resources-page\" style=\"padding-top: var(--wp--preset--spacing--regular); padding-bottom: var(--wp--preset--spacing--regular);\">\n    <div class=\"container\">\n\n        <div class=\"resource-filters\"><span class=\"filter-button-label\">Tipo<\/span><a href=\"https:\/\/mdxcro.com\/es\/blog\/\" class=\"filter-button active\">All<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?category=actualizaciones-normativas\" class=\"filter-button \">Actualizaciones normativas<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?category=blog-2\" class=\"filter-button \">Blog<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?category=casos-practicos\" class=\"filter-button \">Casos pr\u00e1cticos<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?category=eventos-y-congresos\" class=\"filter-button \">Eventos y congresos<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?category=noticias-sobre-ivd\" class=\"filter-button \">Noticias sobre IVD<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?category=sin-categoria\" class=\"filter-button \">Sin categor\u00eda<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?category=whitepapers\" class=\"filter-button \">Whitepapers<\/a><\/div><div class=\"resource-filters\"><span class=\"filter-button-label\">Sector<\/span><a href=\"https:\/\/mdxcro.com\/es\/blog\/\" class=\"filter-button active\">All<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?resources-sector=digital-health-ai\" class=\"filter-button \">Digital Health &amp; AI<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?resources-sector=ivds\" class=\"filter-button \">IVDs<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?resources-sector=laboratories\" class=\"filter-button \">Laboratories<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?resources-sector=medical-devices\" class=\"filter-button \">Medical Devices<\/a><a href=\"https:\/\/mdxcro.com\/es\/blog\/?resources-sector=precision-medicine-cdx\" class=\"filter-button \">Precision Medicine &amp; CDx<\/a><\/div>\n        <div class=\"latest-resources resources-grid resources-grid-4\">                <div class=\"slider-item\">\n                    <a href=\"https:\/\/mdxcro.com\/es\/guia-fda-factores-humanos-2026\/\" class=\"slider-item-link\">\n                        <div class=\"image-wrapper\">\n                                                            <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/06\/Usability-Medical-Devices-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Gu\u00eda de Factores Humanos de la FDA 2026: Qu\u00e9 significa la gu\u00eda final para su presentaci\u00f3n\" \/>                                                    <\/div>\n                        <div class=\"content-wrapper\">\n                            <p class=\"text\">Gu\u00eda de Factores Humanos de la FDA 2026: Qu\u00e9 significa la gu\u00eda final para su presentaci\u00f3n<\/p>\n                        <\/div>\n                    <\/a>\n                    <div class=\"slider-meta\">\n                        <div class=\"slider-meta-col\">\n                            4 de junio de 2026                        <\/div>\n                        <div class=\"slider-meta-col\">\n                            Actualizaciones normativas | Medical Devices                        <\/div>\n                    <\/div>\n                <\/div>\n                                <div class=\"slider-item\">\n                    <a href=\"https:\/\/mdxcro.com\/es\/regulacion-fda-ivd\/\" class=\"slider-item-link\">\n                        <div class=\"image-wrapper\">\n                                                            <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/06\/FDA-IVD-Regulation-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Regulaci\u00f3n de la FDA para dispositivos de diagn\u00f3stico in vitro: La gu\u00eda completa para la entrada en el mercado de EE. UU.\" \/>                                                    <\/div>\n                        <div class=\"content-wrapper\">\n                            <p class=\"text\">Regulaci\u00f3n de la FDA para dispositivos de diagn\u00f3stico in vitro: La gu\u00eda completa para la entrada en el mercado de EE. UU.<\/p>\n                        <\/div>\n                    <\/a>\n                    <div class=\"slider-meta\">\n                        <div class=\"slider-meta-col\">\n                            4 de junio de 2026                        <\/div>\n                        <div class=\"slider-meta-col\">\n                            Actualizaciones normativas | IVDs, Precision Medicine &amp; CDx                        <\/div>\n                    <\/div>\n                <\/div>\n                                <div class=\"slider-item\">\n                    <a href=\"https:\/\/mdxcro.com\/es\/informe-validez-cientifica-ivdr-svr\/\" class=\"slider-item-link\">\n                        <div class=\"image-wrapper\">\n                                                            <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/04\/ivdr-MDx-cRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Informe de Validez Cient\u00edfica (SVR) seg\u00fan el Reglamento IVD de la UE: De la revisi\u00f3n bibliogr\u00e1fica al argumento cient\u00edfico defendible\" \/>                                                    <\/div>\n                        <div class=\"content-wrapper\">\n                            <p class=\"text\">Informe de Validez Cient\u00edfica (SVR) seg\u00fan el Reglamento IVD de la UE: De la revisi\u00f3n bibliogr\u00e1fica al argumento cient\u00edfico defendible<\/p>\n                        <\/div>\n                    <\/a>\n                    <div class=\"slider-meta\">\n                        <div class=\"slider-meta-col\">\n                            1 de junio de 2026                        <\/div>\n                        <div class=\"slider-meta-col\">\n                            Noticias sobre IVD | IVDs                        <\/div>\n                    <\/div>\n                <\/div>\n                                <div class=\"slider-item\">\n                    <a href=\"https:\/\/mdxcro.com\/es\/mdcg-2021-24-rev-1-clasificacion-mdr\/\" class=\"slider-item-link\">\n                        <div class=\"image-wrapper\">\n                                                            <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/03\/MDCG-Documentations-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"MDCG 2021-24 Rev.1: Qu\u00e9 ha cambiado en la clasificaci\u00f3n de dispositivos del MDR de la UE (abril de 2026)\" \/>                                                    <\/div>\n                        <div class=\"content-wrapper\">\n                            <p class=\"text\">MDCG 2021-24 Rev.1: Qu\u00e9 ha cambiado en la clasificaci\u00f3n de dispositivos del MDR de la UE (abril de 2026)<\/p>\n                        <\/div>\n                    <\/a>\n                    <div class=\"slider-meta\">\n                        <div class=\"slider-meta-col\">\n                            26 de mayo de 2026                        <\/div>\n                        <div class=\"slider-meta-col\">\n                            Actualizaciones normativas | Medical Devices                        <\/div>\n                    <\/div>\n                <\/div>\n                                <div class=\"slider-item\">\n                    <a href=\"https:\/\/mdxcro.com\/es\/iso-10993-1-2025-biocompatibilidad\/\" class=\"slider-item-link\">\n                        <div class=\"image-wrapper\">\n                                                            <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/05\/iso-10993-1-2025-biocompatibility-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"ISO 10993-1:2025: del cumplimiento, a la biocompatibilidad basada en riesgos\" \/>                                                    <\/div>\n                        <div class=\"content-wrapper\">\n                            <p class=\"text\">ISO 10993-1:2025: del cumplimiento, a la biocompatibilidad basada en riesgos<\/p>\n                        <\/div>\n                    <\/a>\n                    <div class=\"slider-meta\">\n                        <div class=\"slider-meta-col\">\n                            11 de mayo de 2026                        <\/div>\n                        <div class=\"slider-meta-col\">\n                            Blog, Whitepapers | Medical Devices                        <\/div>\n                    <\/div>\n                <\/div>\n                                <div class=\"slider-item\">\n                    <a href=\"https:\/\/mdxcro.com\/es\/fda-diagnostico-complementario\/\" class=\"slider-item-link\">\n                        <div class=\"image-wrapper\">\n                                                            <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/04\/Leading-IVD-CRO-in-Europe-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Diagn\u00f3stico complementario de la FDA: Gu\u00eda regulatoria completa para el desarrollo, aprobaci\u00f3n y estrategia de codesarrollo de CDx\" \/>                                                    <\/div>\n                        <div class=\"content-wrapper\">\n                            <p class=\"text\">Diagn\u00f3stico complementario de la FDA: Gu\u00eda regulatoria completa para el desarrollo, aprobaci\u00f3n y estrategia de codesarrollo de CDx<\/p>\n                        <\/div>\n                    <\/a>\n                    <div class=\"slider-meta\">\n                        <div class=\"slider-meta-col\">\n                            7 de mayo de 2026                        <\/div>\n                        <div class=\"slider-meta-col\">\n                            Actualizaciones normativas, Whitepapers | Precision Medicine &amp; CDx                        <\/div>\n                    <\/div>\n                <\/div>\n                <\/div><div class=\"pagination\" data-total-pages=\"15\"><span class=\"prev button disabled\">Prev<\/span><span class=\"page-count\">1 of 15<\/span><a class=\"next button\" href=\"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/pages\/7184\/page\/2\/\">Next<\/a><\/div>\n    <\/div>\n<\/section>\n\n\n<section id=\"block_94b3a748f6eb77144495aa3e332f7d56\" class=\"content-columns content-columns--four-columns content-columns--background-blue\" style=\"\">\n        <div class=\"container\">\n        \n                    <div class=\"grid\">\n                                                        <div class=\"card card--background-white-frost card--value\">\n                                            <div class=\"top\">\n                                                          <div class=\"circle\">\n                                                                                              <div class=\"value\">Blog &amp; recursos<\/div>\n                                                            <\/div>\n                                                                                                                    <div class=\"teaser wysiwyg\"><p>Donde nuestro equipo desglosa lo \u00faltimo en la regulaci\u00f3n de productos sanitarios de la UE, con an\u00e1lisis pr\u00e1cticos, comentarios de expertos y las perspectivas que aportamos al trabajar con fabricantes cada d\u00eda.<\/p>\n<\/div>\n                                                    <\/div>\n                                                                    <\/div>\n                                                                            <div class=\"card card--background-white-frost card--value\">\n                                            <div class=\"top\">\n                                                          <div class=\"circle\">\n                                                                                              <div class=\"value\">Casos pr\u00e1cticos<\/div>\n                                                            <\/div>\n                                                                                                                    <div class=\"teaser wysiwyg\"><p>Proyectos reales, resultados reales. Vea c\u00f3mo hemos ayudado a los fabricantes a navegar por evaluaciones cl\u00ednicas, transiciones al IVDR y evaluaciones de conformidad complejas en toda Europa.<\/p>\n<\/div>\n                                                    <\/div>\n                                                                    <\/div>\n                                                                            <div class=\"card card--background-white-frost card--value\">\n                                            <div class=\"top\">\n                                                          <div class=\"circle\">\n                                                                                              <div class=\"value\">Actualizaciones normativas<\/div>\n                                                            <\/div>\n                                                                                                                    <div class=\"teaser wysiwyg\"><p>Nuevas gu\u00edas del MDCG, normas armonizadas revisadas, plazos regulatorios; realizamos un seguimiento de los cambios para que pueda actuar sobre ellos antes de que se conviertan en problemas.<\/p>\n<\/div>\n                                                    <\/div>\n                                                                    <\/div>\n                                                                            <div class=\"card card--background-white-frost card--value\">\n                                            <div class=\"top\">\n                                                          <div class=\"circle\">\n                                                                                              <div class=\"value\">Recursos gratuitos<\/div>\n                                                            <\/div>\n                                                                                                                    <div class=\"teaser wysiwyg\"><p>Plantillas, listas de verificaci\u00f3n, libros blancos y grabaciones de seminarios web. Las mismas herramientas que nuestro equipo utiliza internamente, disponibles para ayudarle a avanzar m\u00e1s r\u00e1pido.<\/p>\n<\/div>\n                                                    <\/div>\n                                                                    <\/div>\n                                                <\/div>\n                  \n          \n\n            <\/div>\n<\/section>\n\n\n\n<section class=\"latest-resources\"  style=\"\">\n    <div class=\"container\">\n      <\/div>\n\n      <div class=\"slider\">\n      <div class=\"slider-inner\">\n                            <a href=\"https:\/\/mdxcro.com\/how-to-choose-notified-body-mdr-ivdr\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Sectors-services-transversal-strenght-vertical-specialization-800x530.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"High-quality image of a person interacting with digital certification and approval icons on a laptop, emphasizing MedTech innovation, compliance, and accelerated medical technology solutions.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">How to Choose a Notified Body for Medical Devices and IVDs<\/p>\n            <\/div>\n          <\/a>\n                            <a href=\"https:\/\/mdxcro.com\/medical-device-industry-trends\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/08\/Medical-Device-Industry-Trends-2026-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Medical devices and wearable health technology with digital data analytics and global connectivity.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">Medical Device Industry Trends 2026: Where the Market Is Growing, and Why the Forecasts Disagree<\/p>\n            <\/div>\n          <\/a>\n                            <a href=\"https:\/\/mdxcro.com\/es\/guia-fda-factores-humanos-2026\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/06\/Usability-Medical-Devices-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Diversos profesionales sanitarios uniendo sus manos en un gesto de equipo, simbolizando la colaboraci\u00f3n y la unidad en la pr\u00e1ctica m\u00e9dica.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">Gu\u00eda de Factores Humanos de la FDA 2026: Qu\u00e9 significa la gu\u00eda final para su presentaci\u00f3n<\/p>\n            <\/div>\n          <\/a>\n                            <a href=\"https:\/\/mdxcro.com\/fda-human-factors-guidance-2026\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/06\/Usability-Medical-Devices-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Diverse healthcare professionals joining hands in a team-building gesture, symbolizing collaboration and unity in medical practice.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">FDA Human Factors Guidance 2026: What the Final Guidance Means for Your Submission<\/p>\n            <\/div>\n          <\/a>\n                            <a href=\"https:\/\/mdxcro.com\/es\/regulacion-fda-ivd\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/06\/FDA-IVD-Regulation-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Una aguja dispensando medicaci\u00f3n en un tubo de ensayo en un entorno de laboratorio, enfatizando la precisi\u00f3n y las t\u00e9cnicas est\u00e9riles para la investigaci\u00f3n m\u00e9dica y el diagn\u00f3stico.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">Regulaci\u00f3n de la FDA para dispositivos de diagn\u00f3stico in vitro: La gu\u00eda completa para la entrada en el mercado de EE. UU.<\/p>\n            <\/div>\n          <\/a>\n              <\/div>\n    <\/div>\n  \n  <\/section>\n\n\n\n<style>.mdx-banner {\n  margin-left:  calc(var(--container-padding, 20px) * -1);\n  margin-right: calc(var(--container-padding, 20px) * -1);\n  overflow: hidden;\n}\n\n.mdx-banner-carousel {\n  width: 100%;\n  overflow: hidden;\n  position: relative;\n  height: 45vh;\n  min-height: 280px;\n  background: #000;\n}\n\n.mdx-banner-carousel::after {\n  content: '';\n  position: absolute;\n  bottom: 0;\n  left: 0;\n  right: 0;\n  top: auto;\n  height: 35%;\n  background: linear-gradient(to bottom,\n    rgba(255,255,255,0) 0%,\n    rgba(255,255,255,0.7) 60%,\n    rgba(255,255,255,1) 100%);\n  pointer-events: none;\n  z-index: 3;\n}\n\n.mdx-banner-track {\n  display: flex;\n  gap: 3px;\n  width: max-content;\n  height: 100%;\n  animation: mdxBannerScroll 30s linear infinite;\n  will-change: transform;\n}\n.mdx-banner-track:hover { animation-play-state: paused; }\n\n@keyframes mdxBannerScroll {\n  0%   { transform: translateX(0); }\n  100% { transform: translateX(-50%); }\n}\n\n.mdx-banner-photo {\n  flex-shrink: 0;\n  width: calc((100vw - 15px) \/ 6);\n  height: 100%;\n  overflow: hidden;\n  position: relative;\n}\n\n.mdx-banner-photo img {\n  width: 100%;\n  height: 100%;\n  object-fit: cover;\n  object-position: top center;\n  filter: grayscale(100%);\n  display: block;\n}\n\n@media (max-width: 860px) {\n  .mdx-banner-photo { width: calc((100vw - 9px) \/ 4); }\n}\n@media (max-width: 520px) {\n  .mdx-banner-photo { width: calc((100vw - 6px) \/ 3); }\n}\n<\/style><div class=\"mdx-banner\"><div class=\"mdx-banner-carousel\"><div class=\"mdx-banner-track\"><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/10\/Carlos-Galamba-2.jpg\" alt=\"Carlos Galamba\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/01\/Joana-Martins-Team-MDxCRO.png.webp\" alt=\"Joana Martins\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Yaiza-Benito.jpeg\" alt=\"Yaiza Benito\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Callum-Pickett.jpeg\" alt=\"Callum Pickett\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Floella-Otudeko.jpeg\" alt=\"Floella Otudeko\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Alberto-Bardaji.jpeg\" alt=\"Alberto Bardaji\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Andre-Moreira.jpeg\" alt=\"Andre Moreira\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/10\/Carlos-Galamba-2.jpg\" alt=\"\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/01\/Joana-Martins-Team-MDxCRO.png.webp\" alt=\"\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Yaiza-Benito.jpeg\" alt=\"\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Callum-Pickett.jpeg\" alt=\"\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Floella-Otudeko.jpeg\" alt=\"\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Alberto-Bardaji.jpeg\" alt=\"\" loading=\"lazy\"\/><\/div><div class=\"mdx-banner-photo\"><img decoding=\"async\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/Andre-Moreira.jpeg\" alt=\"\" loading=\"lazy\"\/><\/div><\/div><\/div><\/div>\n\n\n\n<section id=\"block_b316301f88a75df8a287ae89326409b4\" class=\"text-image\" style=\"\">\n        <div class=\"container\">\n        <div class=\"grid\">\n            <div class=\"column column--content\"><div class=\"text\"><h2 class=\"title\">Inteligencia regulatoria de m\u00e1s de 40 especialistas<\/h2><div class=\"description wysiwyg\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Nuestro contenido est\u00e1 escrito por un equipo multidisciplinar de m\u00e1s de 40 profesionales: antiguos revisores de autoridades competentes nacionales, auditores de organismos notificados, asociados de investigaci\u00f3n cl\u00ednica e ingenieros biom\u00e9dicos, cada uno con experiencia pr\u00e1ctica navegando el MDR y el IVDR.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cada art\u00edculo, libro blanco y recurso que publicamos se basa en el trabajo que realizamos a diario para los fabricantes: redacci\u00f3n de informes de evaluaci\u00f3n cl\u00ednica, dise\u00f1o de investigaciones cl\u00ednicas, compilaci\u00f3n de documentaci\u00f3n t\u00e9cnica y apoyo en evaluaciones de conformidad en toda Europa.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Esto no es un comentario regulatorio reciclado. Es material pr\u00e1ctico centrado en el fabricante, creado a partir de la experiencia en proyectos reales, la misma pericia que aplicamos al trabajar con nuestros clientes.<\/p>\n<\/div><\/div><\/div>                            <div class=\"column column--image\"><img decoding=\"async\" class=\"image\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/09\/marketa-huiwen-scaled.jpg\" alt=\"\"  \/><\/div>                    <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"latest-resources\"  style=\"\">\n    <div class=\"container\">\n          <div class=\"headline\">Perspectivas y actualizaciones<a href=\"#\" class=\"slider-nav slider-nav-left\"><\/a><a href=\"#\" class=\"slider-nav slider-nav-right\"><\/a><\/div>\n      <\/div>\n\n      <div class=\"slider\">\n      <div class=\"slider-inner\">\n                            <a href=\"https:\/\/mdxcro.com\/es\/iso-10993-1-2025-biocompatibilidad\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/05\/iso-10993-1-2025-biocompatibility-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Primer plano de un modelo transparente de doble h\u00e9lice de ADN que simboliza la biocompatibilidad y la innovaci\u00f3n en tecnolog\u00eda m\u00e9dica.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">ISO 10993-1:2025: del cumplimiento, a la biocompatibilidad basada en riesgos<\/p>\n            <\/div>\n          <\/a>\n                            <a href=\"https:\/\/mdxcro.com\/es\/ivdr-estudios-combinados\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/Clinical-research-MDx-CRO-1-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Investigadores realizando experimentos avanzados de tecnolog\u00eda m\u00e9dica en un entorno de laboratorio, centrados en la investigaci\u00f3n cl\u00ednica y en soluciones innovadoras para la atenci\u00f3n sanitaria.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">Gu\u00eda pr\u00e1ctica: IVDR en estudios combinados desde 40+ programas de investigaci\u00f3n<\/p>\n            <\/div>\n          <\/a>\n                            <a href=\"https:\/\/mdxcro.com\/es\/iso-14155-2026\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/regulatory-cpmpliance-technical-documentation-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Fabricaci\u00f3n automatizada de viales m\u00e9dicos en un entorno de sala limpia, destacando los avances de MedTech por MDX para las industrias de dispositivos m\u00e9dicos y farmac\u00e9utica.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">ISO 14155:2026: \u00bfQu\u00e9 ha cambiado y qu\u00e9 implica para su investigaci\u00f3n cl\u00ednica?<\/p>\n            <\/div>\n          <\/a>\n                            <a href=\"https:\/\/mdxcro.com\/es\/nueva-ley-ensayos-clinicos-portugal-2026\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/clinical-research-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Primer plano de un cient\u00edfico manipulando un tubo de ensayo con cadenas de ADN y superposiciones de datos m\u00e9dicos digitales, enfatizando la tecnolog\u00eda m\u00e9dica avanzada y la investigaci\u00f3n.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">Nueva Ley de Ensayos Cl\u00ednicos de Portugal n.\u00ba 9\/2026: Lo que los sponsors deben saber<\/p>\n            <\/div>\n          <\/a>\n                            <a href=\"https:\/\/mdxcro.com\/es\/imdrf-n91-evidencia-clinica-ivd-2026\/\" class=\"slider-item\">\n            <div class=\"image-wrapper\">\n                              <img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2026\/03\/MDCG-Documentations-MDx-CRO-800x530.webp\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Una pila alta de documentaci\u00f3n organizada de productos sanitarios y documentos regulatorios sobre un fondo azul, enfatizando el cumplimiento y los est\u00e1ndares regulatorios en MedTech.\" \/>                          <\/div>\n            <div class=\"content-wrapper\">\n              <p class=\"text\">IMDRF N91 2026: Nuevos Requisitos de Evidencia Cl\u00ednica para Dispositivos IVD<\/p>\n            <\/div>\n          <\/a>\n              <\/div>\n    <\/div>\n  \n  <\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":10067,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7184","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recursos: MedTech, CDx, Informaci\u00f3n sobre IVDR\/MDR | MDx CRO<\/title>\n<meta name=\"description\" content=\"Blogs, casos pr\u00e1cticos y actualizaciones regulatorias sobre IVDR, MDR, NGS y diagn\u00f3sticos complementarios. Recursos seleccionados por MDx CRO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mdxcro.com\/es\/recursos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recursos: MedTech, CDx, Informaci\u00f3n sobre IVDR\/MDR | MDx CRO\" \/>\n<meta property=\"og:description\" content=\"Blogs, casos pr\u00e1cticos y actualizaciones regulatorias sobre IVDR, MDR, NGS y diagn\u00f3sticos complementarios. Recursos seleccionados por MDx CRO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mdxcro.com\/es\/recursos\/\" \/>\n<meta property=\"og:site_name\" content=\"MDx CRO\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T06:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/RA-technical-documentations-MDx-CRO.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/recursos\\\/\",\"url\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/recursos\\\/\",\"name\":\"Recursos: MedTech, CDx, Informaci\u00f3n sobre IVDR\\\/MDR | MDx CRO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/recursos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/recursos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mdxcro.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/RA-technical-documentations-MDx-CRO.webp\",\"datePublished\":\"2025-07-29T13:53:41+00:00\",\"dateModified\":\"2026-06-03T06:39:59+00:00\",\"description\":\"Blogs, casos pr\u00e1cticos y actualizaciones regulatorias sobre IVDR, MDR, NGS y diagn\u00f3sticos complementarios. Recursos seleccionados por MDx CRO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/recursos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mdxcro.com\\\/es\\\/recursos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/recursos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mdxcro.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/RA-technical-documentations-MDx-CRO.webp\",\"contentUrl\":\"https:\\\/\\\/mdxcro.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/RA-technical-documentations-MDx-CRO.webp\",\"width\":1920,\"height\":960,\"caption\":\"MDX's innovative platform supports MedTech companies in accelerating product development and regulatory documentation through advanced digital solutions.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/recursos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recursos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/\",\"name\":\"MDx CRO\",\"description\":\"Investigaci\u00f3n cl\u00ednica, normativa y control de calidad en tecnolog\u00eda m\u00e9dica y diagn\u00f3stico in vitro\",\"publisher\":{\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/#organization\"},\"alternateName\":\"MDx\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/#organization\",\"name\":\"CRO de MDx\",\"url\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mdxcro.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/MDX.svg\",\"contentUrl\":\"https:\\\/\\\/mdxcro.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/MDX.svg\",\"width\":352,\"height\":114,\"caption\":\"CRO de MDx\"},\"image\":{\"@id\":\"https:\\\/\\\/mdxcro.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/medtech-ivd-cro\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recursos: MedTech, CDx, Informaci\u00f3n sobre IVDR\/MDR | MDx CRO","description":"Blogs, casos pr\u00e1cticos y actualizaciones regulatorias sobre IVDR, MDR, NGS y diagn\u00f3sticos complementarios. Recursos seleccionados por MDx CRO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mdxcro.com\/es\/recursos\/","og_locale":"es_ES","og_type":"article","og_title":"Recursos: MedTech, CDx, Informaci\u00f3n sobre IVDR\/MDR | MDx CRO","og_description":"Blogs, casos pr\u00e1cticos y actualizaciones regulatorias sobre IVDR, MDR, NGS y diagn\u00f3sticos complementarios. Recursos seleccionados por MDx CRO.","og_url":"https:\/\/mdxcro.com\/es\/recursos\/","og_site_name":"MDx CRO","article_modified_time":"2026-06-03T06:39:59+00:00","og_image":[{"width":1920,"height":960,"url":"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/RA-technical-documentations-MDx-CRO.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mdxcro.com\/es\/recursos\/","url":"https:\/\/mdxcro.com\/es\/recursos\/","name":"Recursos: MedTech, CDx, Informaci\u00f3n sobre IVDR\/MDR | MDx CRO","isPartOf":{"@id":"https:\/\/mdxcro.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mdxcro.com\/es\/recursos\/#primaryimage"},"image":{"@id":"https:\/\/mdxcro.com\/es\/recursos\/#primaryimage"},"thumbnailUrl":"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/RA-technical-documentations-MDx-CRO.webp","datePublished":"2025-07-29T13:53:41+00:00","dateModified":"2026-06-03T06:39:59+00:00","description":"Blogs, casos pr\u00e1cticos y actualizaciones regulatorias sobre IVDR, MDR, NGS y diagn\u00f3sticos complementarios. Recursos seleccionados por MDx CRO.","breadcrumb":{"@id":"https:\/\/mdxcro.com\/es\/recursos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mdxcro.com\/es\/recursos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mdxcro.com\/es\/recursos\/#primaryimage","url":"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/RA-technical-documentations-MDx-CRO.webp","contentUrl":"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/RA-technical-documentations-MDx-CRO.webp","width":1920,"height":960,"caption":"MDX's innovative platform supports MedTech companies in accelerating product development and regulatory documentation through advanced digital solutions."},{"@type":"BreadcrumbList","@id":"https:\/\/mdxcro.com\/es\/recursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mdxcro.com\/es\/"},{"@type":"ListItem","position":2,"name":"Recursos"}]},{"@type":"WebSite","@id":"https:\/\/mdxcro.com\/es\/#website","url":"https:\/\/mdxcro.com\/es\/","name":"MDx CRO","description":"Investigaci\u00f3n cl\u00ednica, normativa y control de calidad en tecnolog\u00eda m\u00e9dica y diagn\u00f3stico in vitro","publisher":{"@id":"https:\/\/mdxcro.com\/es\/#organization"},"alternateName":"MDx","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mdxcro.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mdxcro.com\/es\/#organization","name":"CRO de MDx","url":"https:\/\/mdxcro.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mdxcro.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/MDX.svg","contentUrl":"https:\/\/mdxcro.com\/wp-content\/uploads\/2025\/07\/MDX.svg","width":352,"height":114,"caption":"CRO de MDx"},"image":{"@id":"https:\/\/mdxcro.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/medtech-ivd-cro"]}]}},"_links":{"self":[{"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/pages\/7184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/comments?post=7184"}],"version-history":[{"count":10,"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/pages\/7184\/revisions"}],"predecessor-version":[{"id":11631,"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/pages\/7184\/revisions\/11631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/media\/10067"}],"wp:attachment":[{"href":"https:\/\/mdxcro.com\/es\/wp-json\/wp\/v2\/media?parent=7184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}